{"id":1540,"date":"2022-03-31T16:21:34","date_gmt":"2022-03-31T10:51:34","guid":{"rendered":"https:\/\/darululoom-deoband.com\/urduarticles\/?p=1540"},"modified":"2022-03-31T16:21:37","modified_gmt":"2022-03-31T10:51:37","slug":"%d8%a7%d8%b3%d9%84%d8%a7%d9%85%db%8c-%d8%ac%db%81%d8%a7%d8%af-%da%a9%db%8c-%d8%ad%d9%82%db%8c%d9%82%d8%aa-%d9%82%d8%b1%d8%a2%d9%86-%d9%88%d8%ad%d8%af%db%8c%d8%ab-%da%a9%db%8c-%d8%b1%d9%88%d8%b4%d9%86","status":"publish","type":"post","link":"https:\/\/darululoom-deoband.com\/urduarticles\/archives\/1540","title":{"rendered":"\u0627\u0633\u0644\u0627\u0645\u06cc \u062c\u06c1\u0627\u062f \u06a9\u06cc \u062d\u0642\u06cc\u0642\u062a \u0642\u0631\u0622\u0646 \u0648\u062d\u062f\u06cc\u062b \u06a9\u06cc \u0631\u0648\u0634\u0646\u06cc \u0645\u06cc\u06ba"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">\u0627\u0632:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0645\u0648\u0644\u0627\u0646\u0627\u0646\u0635\u06cc\u0631\u0627\u0644\u062f\u06cc\u0646 \u0642\u0627\u0633\u0645\u06cc \u0648\u0644\u06cc\u062f\u067e\u0648\u0631\u06cc\u060c\u0627\u0633\u062a\u0627\u0630 \u0645\u062f\u0631\u0633\u06c1 \u062f\u0627\u0631\u0627\u0644\u0639\u0644\u0648\u0645 \u0645\u062d\u0645\u062f\u06cc\u06c1 \u0642\u0635\u0628\u06c1 \u06af\u062f\u0631\u067e\u0648\u0631<\/h3>\n\n\n\n<p>\u0627\u0646\u0633\u0627\u0646 \u06a9\u06cc \u062c\u0627\u0646 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u0627 \u062e\u0648\u0646 \u0645\u062d\u062a\u0631\u0645 \u06c1\u06d2\u060c \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0633\u0627\u0631\u06d2 \u0645\u0630\u0627\u06c1\u0628 \u0645\u06cc\u06ba \u0627\u062d\u062a\u0631\u0627\u0645\u0650 \u0646\u0641\u0633 \u06a9\u0627 \u06cc\u06c1 \u0627\u0635\u0648\u0644 \u0645\u0648\u062c\u0648\u062f \u06c1\u06d2 \u0627\u0648\u0631\u062c\u0633 \u0645\u0630\u06c1\u0628 \u0627\u0648\u0631\u0642\u0627\u0646\u0648\u0646 \u0645\u06cc\u06ba \u0627\u0633 \u062f\u0641\u0639\u06c1 \u06a9\u0648 \u062a\u0633\u0644\u06cc\u0645 \u0646\u06c1\u06cc\u06ba \u06a9\u06cc\u0627\u06af\u06cc\u0627\u06c1\u06d2\u060c \u0627\u0633 \u0645\u0630\u06c1\u0628 \u0627\u0648\u0631 \u0642\u0627\u0646\u0648\u0646 \u06a9\u06d2 \u062a\u062d\u062a \u0631\u06c1 \u06a9\u0631 \u06a9\u0648\u0626\u06cc \u0627\u0646\u0633\u0627\u0646 \u067e\u064f\u0631\u0627\u0645\u0646 \u0632\u0646\u062f\u06af\u06cc \u0646\u06c1\u06cc\u06ba \u06af\u0630\u0627\u0631\u0633\u06a9\u062a\u0627 \u06c1\u06d2\u06d4<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0627\u0648\u0631 \u0627\u06af\u0631 \u062e\u0627\u0644\u0635 \u0627\u0646\u0633\u0627\u0646\u06cc\u062a \u06a9\u06cc \u0646\u0638\u0631 \u0633\u06d2 \u062f\u06cc\u06a9\u06be\u0627 \u062c\u0627\u0626\u06d2\u060c \u062a\u0648 \u0627\u0633 \u0644\u062d\u0627\u0638 \u0633\u06d2 \u0628\u06be\u06cc \u06a9\u0633\u06cc \u0630\u0627\u062a\u06cc \u0645\u0641\u0627\u062f \u06a9\u06cc \u062e\u0627\u0637\u0631 \u0627\u067e\u0646\u06d2 \u0628\u06be\u0627\u0626\u06cc \u06a9\u0648 \u0642\u062a\u0644 \u06a9\u0631\u0646\u0627\u060c \u0628\u062f\u062a\u0631\u06cc\u0646 \u062c\u0631\u0645 \u06c1\u06d2\u060c \u062c\u0633 \u06a9\u0627 \u0627\u0631\u062a\u06a9\u0627\u0628 \u06a9\u0631\u06a9\u06d2 \u0627\u0646\u0633\u0627\u0646 \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u0627\u062e\u0644\u0627\u0642\u06cc \u0628\u0644\u0646\u062f\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u0646\u0627 \u062a\u0648 \u062f\u0631 \u06a9\u0646\u0627\u0631\u060c \u0627\u0633 \u06a9\u0627 \u062f\u0631\u062c\u06c1\u0674 \u0627\u0646\u0633\u0627\u0646\u06cc\u062a \u067e\u0631 \u0642\u0627\u0626\u0645 \u0631\u06c1\u0646\u0627 \u0628\u06be\u06cc \u0646\u0627\u0645\u0645\u06a9\u0646 \u06c1\u06d2\u06d4<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0633\u06cc\u0627\u0633\u06cc \u0642\u0648\u0627\u0646\u06cc\u0646\u060c \u062a\u0648 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u062d\u062a\u0631\u0627\u0645 \u06a9\u0648 \u0635\u0631\u0641 \u0633\u0632\u0627 \u06a9\u06d2 \u062e\u0648\u0641 \u0633\u06d2 \u0642\u0648\u062a \u06a9\u06d2 \u0628\u0644 \u0628\u0648\u062a\u06d2 \u067e\u0631 \u0642\u0627\u0626\u0645 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u061b \u0645\u06af\u0631 \u0627\u06cc\u06a9 \u0633\u0686\u06d2 \u062f\u06cc\u0646 \u0648\u0645\u0630\u06c1\u0628 \u06a9\u0627 \u06a9\u0627\u0645 \u0627\u0646\u0633\u0627\u0646\u06cc \u062f\u0644\u0648\u06ba \u0645\u06cc\u06ba \u0627\u0633 \u06a9\u06cc \u0635\u062d\u06cc\u062d \u0642\u062f\u0631 \u0648\u0642\u06cc\u0645\u062a \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u06cc\u062a\u0627 \u06c1\u06d2\u061b \u062a\u0627\u06a9\u06c1 \u062c\u06c1\u0627\u06ba \u0627\u0646\u0633\u0627\u0646\u06cc \u062a\u0639\u0632\u06cc\u0631 \u06a9\u0627 \u062e\u0648\u0641 \u0646\u06c1 \u06c1\u0648\u060c \u0648\u06c1\u0627\u06ba \u0628\u06be\u06cc \u0627\u06cc\u06a9 \u0627\u0646\u0633\u0627\u0646 \u062f\u0648\u0633\u0631\u06d2 \u0627\u0646\u0633\u0627\u0646 \u06a9\u0627 \u062e\u0648\u0646 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u067e\u0631\u06c1\u06cc\u0632 \u06a9\u0631\u06d2\u060c \u0627\u0633 \u0646\u0642\u0637\u0626\u06c1 \u0646\u0638\u0631 \u0633\u06d2 \u0627\u062d\u062a\u0631\u0627\u0645\u0650 \u0646\u0641\u0633 \u06a9\u06cc \u062c\u06cc\u0633\u06cc \u0635\u062d\u06cc\u062d \u0627\u0648\u0631 \u0645\u0648\u0674\u062b\u0631 \u062a\u0639\u0644\u06cc\u0645 \u0627\u0633\u0644\u0627\u0645 \u0645\u06cc\u06ba \u062f\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u060c \u0648\u06c1 \u06a9\u0633\u06cc \u062f\u0648\u0633\u0631\u06d2 \u0627\u0648\u0631 \u0627\u062f\u06cc\u0627\u0646 \u0648\u0645\u0630\u0627\u06c1\u0628 \u0645\u06cc\u06ba \u0646\u0627\u067e\u06cc\u062f \u06c1\u06d2\u060c \u0642\u0631\u0622\u0646 \u06a9\u0631\u06cc\u0645 \u0645\u06cc\u06ba \u0645\u062e\u062a\u0644\u0641 \u062c\u06af\u06c1\u0648\u06ba \u067e\u0631 \u0645\u062e\u062a\u0644\u0641 \u0627\u0646\u062f\u0627\u0632 \u0648\u067e\u06cc\u0631\u0627\u06cc\u06c1 \u0633\u06d2 \u0627\u0633 \u062a\u0639\u0644\u06cc\u0645 \u06a9\u0648 \u0627\u0646\u0633\u0627\u0646\u06cc \u062f\u0644\u0648\u06ba \u0645\u06cc\u06ba \u062f\u0644 \u0646\u0634\u06cc\u06ba \u06a9\u06cc\u0627\u06af\u06cc\u0627 \u06c1\u06d2\u061b \u0686\u0646\u0627\u0646\u0686\u06c1 \u0627\u06cc\u06a9 \u062c\u06af\u06c1 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0646\u06cc\u06a9 \u0628\u0646\u062f\u0648\u06ba \u06a9\u06cc \u0635\u0641\u0627\u062a \u0628\u06cc\u0627\u0646 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0641\u0631\u0645\u0627\u06cc\u0627: \ufd3f \u0648\u064e\u0644\u0627\u064e \u06cc\u064e\u0642\u0652\u062a\u064f\u0644\u064f\u0648\u0652\u0646\u064e \u0627\u0644\u0646\u064e\u0651\u0641\u0652\u0633\u064e \u0627\u0644\u064e\u0651\u062a\u0650\u06cc\u0652 \u062d\u064e\u0631\u064e\u0651\u0645\u064e \u0627\u0644\u0644\u06c1\u064f \u0627\u0650\u0644\u0627\u064e\u0651 \u0628\u0650\u0627\u0644\u0652\u062d\u064e\u0642\u0650\u0651 \u0648\u064e\u0644\u0627\u064e \u06cc\u064e\u0632\u0652\u0646\u064f\u0648\u0652\u0646\u064e \u0648\u064e\u0645\u064e\u0646\u0652 \u06cc\u064e\u0651\u0641\u0652\u0639\u064e\u0644\u0652 \u0630\u0670\u0644\u0650\u06a9\u064e \u06cc\u064e\u0644\u0652\u0642\u064e \u0623\u064e\u062b\u064e\u0627\u0645\u0627\u064b\ufd3e (\u0627\u0644\u0641\u0631\u0642\u0627\u0646:\u06f6\u06f8) \u062a\u0631\u062c\u0645\u06c1: \u201d\u0627\u0648\u0631 \u062c\u0633 \u0630\u0627\u062a \u06a9\u0648 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0646\u06d2 \u062d\u0631\u0627\u0645 \u0641\u0631\u0645\u0627\u06cc\u0627 \u06c1\u06d2 \u0627\u0633 \u06a9\u0648 \u0642\u062a\u0644 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u06c1\u0627\u06ba \u0645\u06af\u0631 \u062d\u0642 \u067e\u0631 \u0627\u0648\u0631 \u0648\u06c1 \u0632\u0646\u0627 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06d2 \u0627\u0648\u0631 \u062c\u0648 \u0634\u062e\u0635 \u0627\u06cc\u0633\u06d2 \u06a9\u0627\u0645 \u06a9\u0631\u06d2 \u06af\u0627 \u062a\u0648 \u0633\u0632\u0627 \u0633\u06d2 \u0627\u0633 \u06a9\u0648 \u0633\u0627\u0628\u0642\u06c1 \u067e\u0691\u06d2 \u06af\u0627\u06d4\u201c<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0627\u0633 \u062a\u0639\u0644\u06cc\u0645 \u06a9\u06d2 \u0627\u0648\u0644\u06cc\u0646 \u0645\u062e\u0627\u0637\u0628 \u0648\u06c1 \u0644\u0648\u06af \u062a\u06be\u06d2\u060c \u062c\u0646 \u06a9\u06d2 \u0646\u0632\u062f\u06cc\u06a9 \u0627\u0646\u0633\u0627\u0646\u06cc \u062c\u0627\u0646 \u0648\u0645\u0627\u0644 \u06a9\u06cc \u06a9\u0648\u0626\u06cc \u0642\u062f\u0631 \u0648\u0642\u06cc\u0645\u062a \u0646\u06c1 \u062a\u06be\u06cc \u0627\u0648\u0631 \u062c\u0648 \u0627\u067e\u0646\u06d2 \u0630\u0627\u062a\u06cc \u0645\u0641\u0627\u062f \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u0648\u0644\u0627\u062f \u062c\u06cc\u0633\u06cc \u0639\u0638\u06cc\u0645 \u0646\u0639\u0645\u062a \u06a9\u0648 \u0628\u06be\u06cc \u0645\u0648\u062a \u06a9\u06d2 \u06af\u06be\u0627\u0679 \u0627\u062a\u0627\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0641\u062e\u0631 \u0645\u062d\u0633\u0648\u0633 \u06a9\u06cc\u0627 \u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2\u061b \u0627\u0633 \u0644\u06cc\u06d2 \u0646\u0628\u06cc \u06a9\u0631\u06cc\u0645 \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u0627\u0646 \u06a9\u06cc \u0637\u0628\u06cc\u0639\u062a\u0648\u06ba \u06a9\u06cc \u0627\u0635\u0644\u0627\u062d \u06a9\u06d2 \u0644\u06cc\u06d2 \u062e\u0648\u062f \u0628\u06be\u06cc \u06c1\u0645\u06cc\u0634\u06c1 \u0627\u062d\u062a\u0631\u0627\u0645\u0650 \u0646\u0641\u0633 \u06a9\u06cc \u062a\u0644\u0642\u06cc\u0646 \u06a9\u06cc\u0627\u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2\u060c \u0627\u062d\u0627\u062f\u06cc\u062b\u0650 \u0645\u0628\u0627\u0631\u06a9\u06c1 \u06a9\u0627 \u0645\u0637\u0627\u0644\u0639\u06c1 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u062d\u0636\u0631\u0627\u062a \u0628\u062e\u0648\u0628\u06cc \u062c\u0627\u0646\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0627\u062d\u0627\u062f\u06cc\u062b \u06a9\u0627 \u0627\u06cc\u06a9 \u0628\u0691\u0627 \u0630\u062e\u06cc\u0631\u06c1 \u0627\u0633 \u0642\u0633\u0645 \u06a9\u06d2 \u0627\u0631\u0634\u0627\u062f\u0627\u062a \u0648\u0628\u06cc\u0627\u0646\u0627\u062a \u0633\u06d2 \u0628\u06be\u0631\u0627 \u067e\u064f\u0631\u0627 \u06c1\u06d2\u060c \u062c\u0633 \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u0646\u0627\u062d\u0642 \u062e\u0648\u0646 \u0628\u06c1\u0627\u0646\u06d2 \u06a9\u0648 \u06af\u0646\u0627\u06c1\u0650 \u0639\u0638\u06cc\u0645 \u0627\u0648\u0631 \u0628\u062f\u062a\u0631\u06cc\u0646 \u062c\u0631\u0645 \u0628\u062a\u0627\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u060c \u062c\u06cc\u0633\u06d2 \u062d\u0636\u0648\u0631 \u0627\u06a9\u0631\u0645 \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u0627 \u0641\u0631\u0645\u0627\u0646 \u06c1\u06d2: \u201d\u0627\u0644\u06a9\u0628\u0627\u0626\u0631\u064f \u0627\u0644\u0627\u0634\u0631\u0627\u06a9\u064f \u0628\u0627\u0644\u0644\u06c1\u0650 \u0648\u0642\u062a\u0644\u064f \u0627\u0644\u0646\u064e\u0641\u0652\u0633\u0650 \u0648\u0639\u0642\u0648\u0642\u064f \u0627\u0644\u0648\u0627\u0644\u062f\u06cc\u0646\u0650 \u0648\u0627\u0644\u06cc\u064e\u0645\u0650\u06cc\u0652\u0646\u064f \u0627\u0644\u063a\u064e\u0645\u064f\u0648\u0633\u064f\u201c (\u0645\u0634\u06a9\u0648\u0670\u0629:\u06f1\u06f7\u060c \u0628\u0627\u0628 \u0627\u0644\u06a9\u0628\u0627\u0626\u0631 \u0648\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u0646\u0641\u0627\u0642) \u062a\u0631\u062c\u0645\u06c1: \u0628\u0691\u06d2 \u06af\u0646\u0627\u06c1\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u0644\u0644\u06c1 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0634\u0631\u06a9 \u06a9\u0631\u0646\u0627\u060c \u062c\u0627\u0646 \u0645\u0627\u0631\u0646\u0627\u060c \u0648\u0627\u0644\u062f\u06cc\u0646 \u06a9\u06cc \u0646\u0627 \u0641\u0631\u0645\u0627\u0646\u06cc \u06a9\u0631\u0646\u0627 \u0627\u0648\u0631 \u062c\u06be\u0648\u0679\u06cc \u0642\u0633\u0645\u06cc\u06ba \u06a9\u06be\u0627\u0646\u0627 \u06c1\u06d2\u06d4<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u062d\u0631\u0645\u062a \u0646\u0641\u0633 \u06a9\u06cc \u06cc\u06c1 \u062a\u0642\u0633\u06cc\u0645 \u06a9\u0633\u06cc \u0641\u0644\u0633\u0641\u06cc \u06cc\u0627 \u0645\u0639\u0644\u0645 \u0627\u062e\u0644\u0627\u0642 \u06a9\u06cc \u0646\u06c1 \u062a\u06be\u06cc \u06a9\u06c1 \u0627\u0633 \u06a9\u0627 \u062f\u0627\u0626\u0631\u0626\u06c1 \u06a9\u0627\u0631 \u0635\u0631\u0641 \u06a9\u062a\u0627\u0628\u0648\u06ba \u06a9\u06cc \u062d\u062f \u062a\u06a9 \u0645\u062d\u062f\u0648\u062f \u0631\u06c1\u062a\u0627\u061b \u0628\u0644\u06a9\u06c1 \u0648\u06c1 \u062e\u062f\u0627 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06d2 \u0631\u0633\u0648\u0644 \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645 \u062a\u06be\u06cc\u060c \u062c\u0646 \u06a9\u0627 \u06c1\u0631 \u06c1\u0631 \u0644\u0641\u0638 \u0645\u0633\u0644\u0645\u0627\u0646\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u06cc\u0645\u0627\u0646 \u0648\u06cc\u0642\u06cc\u0646 \u06a9\u0627 \u062f\u0631\u062c\u06c1 \u0631\u06a9\u06be\u062a\u0627 \u06c1\u06d2\u060c \u062c\u0646 \u06a9\u06cc \u067e\u06cc\u0631\u0648\u06cc \u06c1\u0631 \u0627\u0633 \u0634\u062e\u0635 \u067e\u0631 \u0648\u0627\u062c\u0628 \u0627\u0648\u0631 \u0636\u0631\u0648\u0631\u06cc \u06c1\u0648\u062c\u0627\u062a\u06cc \u06c1\u06d2\u060c \u062c\u0648 \u06a9\u0644\u0645\u06c1\u0674 \u062a\u0648\u062d\u06cc\u062f (\u0644\u0627 \u0627\u0644\u06c1 \u0627\u0644\u0627 \u0627\u0644\u0644\u06c1 \u0645\u062d\u0645\u062f \u0631\u0633\u0648\u0644 \u0627\u0644\u0644\u06c1) \u06a9\u0627 \u0627\u0642\u0631\u0627\u0631 \u06a9\u0631\u062a\u0627 \u06c1\u0648\u061b \u0686\u0646\u0627\u0646\u0686\u06c1 \u0627\u06cc\u06a9 \u0686\u0648\u062a\u06be\u0627\u0626\u06cc \u0635\u062f\u06cc \u06a9\u06d2 \u0642\u0644\u06cc\u0644 \u0639\u0631\u0635\u06c1 \u0645\u06cc\u06ba \u06c1\u06cc \u0627\u0633 \u062a\u0639\u0644\u06cc\u0645 \u06a9\u06cc \u0628\u062f\u0648\u0644\u062a \u0639\u0631\u0628 \u062c\u06cc\u0633\u06cc \u062e\u0648\u0646\u062e\u0648\u0627\u0631 \u0627\u0648\u0631 \u062c\u0627\u0646\u0648\u0631 \u0646\u0645\u0627 \u0642\u0648\u0645 \u06a9\u06d2 \u0627\u0646\u062f\u0631\u0627\u062d\u062a\u0631\u0627\u0645\u0650 \u0646\u0641\u0633 \u0627\u0648\u0631 \u0627\u0645\u0646 \u067e\u0633\u0646\u062f\u06cc \u06a9\u0627 \u0627\u06cc\u0633\u0627 \u0645\u0627\u062f\u06c1 \u067e\u06cc\u062f\u0627\u06c1\u0648\u0627 \u06a9\u06c1 \u0627\u06cc\u06a9 \u0639\u0648\u0631\u062a \u0631\u0627\u062a \u06a9\u06cc \u062a\u0627\u0631\u06cc\u06a9\u06cc \u0645\u06cc\u06ba \u062a\u0646\u0650 \u062a\u0646\u06c1\u0627 \u0642\u0627\u062f\u0633\u06cc\u06c1 \u0633\u06d2 \u0635\u0646\u0639\u0627 \u062a\u06a9 \u0633\u0641\u0631 \u06a9\u0631\u062a\u06cc \u062a\u06be\u06cc \u0627\u0648\u0631 \u06a9\u0648\u0626\u06cc \u0627\u0633 \u06a9\u06cc \u062c\u0627\u0646 \u0648\u0645\u0627\u0644 \u067e\u0631 \u062d\u0645\u0644\u06c1 \u0646\u06c1 \u06a9\u0631\u062a\u0627 \u062a\u06be\u0627 \u0627\u0648\u0631 \u0628\u06c1 \u062d\u0641\u0627\u0638\u062a \u0648\u06c1 \u0627\u067e\u0646\u06cc \u0645\u0646\u0632\u0644 \u062a\u06a9 \u067e\u06c1\u0648\u0646\u0686 \u062c\u0627\u06cc\u0627 \u06a9\u0631\u062a\u06cc \u062a\u06be\u06cc\u061b \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u06cc\u06c1 \u0627\u0646\u06be\u06cc\u06ba \u062f\u0631\u0646\u062f\u0648\u06ba \u0627\u0648\u0631 \u0644\u0679\u06cc\u0631\u0648\u06ba \u06a9\u0627 \u0634\u06c1\u0631 \u0627\u0648\u0631 \u0645\u0644\u06a9 \u062a\u06be\u0627\u060c \u062c\u06c1\u0627\u06ba \u0628\u0691\u06d2 \u0628\u0691\u06d2 \u062f\u0644 \u06af\u0631\u062f\u06d2 \u0648\u0627\u0644\u06d2 \u0628\u06be\u06cc \u06af\u0630\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0644\u0631\u0632\u062c\u0627\u06cc\u0627 \u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2\u060c \u06af\u0648\u06cc\u0627 \u06a9\u06c1 \u062d\u06cc\u0648\u0627\u0646\u06cc\u062a \u0627\u0648\u0631 \u0642\u0633\u0627\u0648\u062a\u0650 \u0642\u0644\u0628\u06cc \u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0639\u0627\u0645 \u0628\u0627\u062a \u062a\u06be\u06cc\u060c \u0627\u06cc\u0633\u06d2 \u0633\u0646\u06af\u06cc\u0646 \u062d\u0627\u0644\u0627\u062a \u0645\u06cc\u06ba \u0627\u0633\u0644\u0627\u0645 \u0646\u06d2 \u0628\u0628\u0627\u0646\u06af\u0650 \u062f\u064f\u06c1\u064f\u0644 \u06cc\u06c1 \u0622\u0648\u0627\u0632 \u0628\u0644\u0646\u062f \u06a9\u06cc: \ufd3f\u0648\u064e\u0644\u0627\u064e \u06cc\u064e\u0642\u0652\u062a\u064f\u0644\u064f\u0648\u0652\u0646\u064e \u0627\u0644\u0646\u064e\u0651\u0641\u0652\u0633\u064e \u0627\u0644\u064e\u0651\u062a\u0650\u06cc\u0652 \u062d\u064e\u0631\u064e\u0651\u0645\u064e \u0627\u0644\u0644\u06c1\u064f \u0627\u0650\u0644\u0627\u064e\u0651 \u0628\u0650\u0627\u0644\u0652\u062d\u064e\u0642\u0650\u0651\ufd3e (\u0627\u0644\u0641\u0631\u0642\u0627\u0646:\u06f6\u06f8) \u201d\u06cc\u0639\u0646\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u062c\u0627\u0646 \u06a9\u0648 \u0627\u0644\u0644\u06c1 \u0646\u06d2 \u062d\u0631\u0627\u0645 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u06c1\u06d2\u060c\u0627\u0633 \u06a9\u0648 \u0646\u0627\u062d\u0642 \u0642\u062a\u0644 \u0645\u062a \u06a9\u0631\u0648\u061b \u0645\u06af\u0631 \u0627\u0633 \u0648\u0642\u062a \u062c\u0628 \u06a9\u06c1 \u062d\u0642 \u0627\u0633 \u06a9\u06d2 \u0642\u062a\u0644 \u06a9\u0627 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u0631\u06d2\u201c \u0627\u0633 \u0622\u0648\u0627\u0632 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0642\u0648\u062a \u0648\u0637\u0627\u0642\u062a \u062a\u06be\u06cc\u061b \u0627\u0633 \u0644\u06cc\u06d2 \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u06af\u0648\u0634\u06c1 \u06af\u0648\u0634\u06c1 \u0645\u06cc\u06ba \u067e\u06c1\u0648\u0646\u0686\u06cc \u0627\u0648\u0631 \u0627\u0633 \u0646\u06d2 \u0627\u0646\u0633\u0627\u0646\u0648\u06ba \u06a9\u0648 \u0627\u067e\u0646\u06cc \u062c\u0627\u0646 \u06a9\u06cc \u0635\u062d\u06cc\u062d \u0642\u062f\u0631 \u0648\u0642\u06cc\u0645\u062a \u0633\u06d2 \u0622\u06af\u0627\u06c1 \u06a9\u06cc\u0627\u060c \u062e\u0648\u0627\u06c1 \u06a9\u0633\u06cc \u0642\u0648\u0645 \u0648\u0645\u0644\u062a \u0646\u06d2 \u06cc\u0627 \u06a9\u0633\u06cc \u0645\u0644\u06a9 \u0648\u0634\u06c1\u0631 \u0646\u06d2 \u0627\u0633\u0644\u0627\u0645 \u06a9\u0648 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u06cc\u0627 \u06c1\u0648 \u06cc\u0627 \u0646\u06c1 \u06a9\u06cc\u0627\u06c1\u0648\u060c \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062a\u0627\u0631\u06cc\u062e \u06a9\u0627 \u06a9\u0648\u0626\u06cc \u0628\u06be\u06cc \u0627\u0646\u0635\u0627\u0641 \u067e\u0633\u0646\u062f \u0627\u0646\u0633\u0627\u0646 \u0627\u0633 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u0633\u06a9\u062a\u0627 \u06a9\u06c1 \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0627\u062e\u0644\u0627\u0642 \u0648\u0642\u0648\u0627\u0646\u06cc\u0646 \u0645\u06cc\u06ba \u0627\u0646\u0633\u0627\u0646\u06cc \u062c\u0627\u0646 \u06a9\u06cc \u062d\u0631\u0645\u062a \u0648\u06a9\u0631\u0627\u0645\u062a \u0642\u0627\u0626\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u062c\u0648 \u0641\u062e\u0631 \u0645\u0630\u06c1\u0628\u0650 \u0627\u0633\u0644\u0627\u0645 \u06a9\u0648 \u062d\u0627\u0635\u0644 \u06c1\u06d2 \u0648\u06c1 \u06a9\u0633\u06cc \u062f\u0648\u0633\u0631\u06d2 \u0627\u062f\u06cc\u0627\u0646 \u0648\u0645\u0630\u0627\u06c1\u0628 \u06a9\u0648 \u062d\u0627\u0635\u0644 \u0646\u06c1\u06cc\u06ba\u06d4<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u063a\u0648\u0631 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u06cc\u06c1 \u0628\u0627\u062a \u0648\u0627\u0636\u062d \u06c1\u0648\u062c\u0627\u062a\u06cc \u06c1\u06d2 \u06a9\u06c1 \ufd3f\u0648\u064e\u0644\u0627\u064e \u06cc\u064e\u0642\u0652\u062a\u064f\u0644\u064f\u0648\u0652\u0646\u064e \u0627\u0644\u0646\u064e\u0651\u0641\u0652\u0633\u064e \u0627\u0644\u064e\u0651\u062a\u0650\u06cc\u0652 \u062d\u064e\u0631\u064e\u0651\u0645\u064e \u0627\u0644\u0644\u06c1\u064f\ufd3e \u06c1\u06cc \u0646\u06c1\u06cc\u06ba \u0641\u0631\u0645\u0627\u06cc\u0627\u061b \u0628\u0644\u06a9\u06c1 \ufd3f\u0627\u0650\u0644\u0627\u064e\u0651 \u0628\u0650\u0627\u0644\u0652\u062d\u064e\u0642\u0650\u0651\ufd3e \u0628\u06be\u06cc \u06a9\u06c1\u0627 \u06af\u06cc\u0627\u060c \u0627\u06cc\u0633\u06d2 \u06c1\u06cc \ufd3f\u0645\u064e\u0646\u0652 \u0642\u064e\u062a\u064e\u0644\u064e \u0646\u064e\u0641\u0652\u0633\u0627\u064b \u0641\u064e\u06a9\u064e\u0627\u064e\u0646\u064e\u0651\u0645\u064e\u0627 \u0642\u064e\u062a\u064e\u0644\u064e \u0627\u0644\u0646\u064e\u0651\u0627\u0633\u064e \u062c\u064e\u0645\u0650\u06cc\u0652\u0639\u0627\u064b\ufd3e \u06c1\u06cc \u0646\u06c1\u06cc\u06ba \u0641\u0631\u0645\u0627\u06cc\u0627\u061b \u0628\u0644\u06a9\u06c1 \u0627\u0633 \u06a9\u06d2 \u0633\u0627\u062a\u06be \ufd3f\u0628\u0650\u063a\u064e\u06cc\u0652\u0631\u0650 \u0646\u064e\u0641\u0652\u0633\u064d \u0627\u064e\u0648\u0652 \u0641\u064e\u0633\u064e\u0627\u062f\u064d \u0641\u0650\u06cc\u0652 \u0627\u0644\u0652\u0627\u064e\u0631\u0652\u0636\u0650\ufd3e \u0628\u06be\u06cc \u06a9\u06c1\u0627 \u06af\u06cc\u0627\u060c \u06cc\u06c1 \u0646\u06c1\u06cc\u06ba \u06a9\u06c1 \u06a9\u0633\u06cc \u0628\u06be\u06cc \u062c\u0627\u0646 \u06a9\u0648 \u06a9\u0633\u06cc \u0628\u06be\u06cc \u062d\u0627\u0644 \u0645\u06cc\u06ba \u0642\u062a\u0644 \u0645\u062a \u06a9\u0631\u0648\u060c \u0627\u06af\u0631 \u0627\u06cc\u0633\u0627 \u06a9\u06c1\u0627 \u062c\u0627\u062a\u0627 \u060c \u062a\u0648 \u06cc\u06c1 \u0639\u062f\u0644 \u06a9\u06d2 \u0628\u0627\u0644\u06a9\u0644 \u062e\u0644\u0627\u0641 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba\u061b \u0628\u0644\u06a9\u06c1 \u062d\u0642\u06cc\u0642\u06cc \u0638\u0644\u0645 \u06c1\u0648\u062a\u0627\u060c \u062f\u0646\u06cc\u0627 \u06a9\u0648 \u0627\u0635\u0644 \u0636\u0631\u0648\u0631\u062a \u0627\u0633 \u0628\u0627\u062a \u06a9\u06cc \u0646\u06c1 \u062a\u06be\u06cc \u06a9\u06c1 \u0627\u0646\u0633\u0627\u0646 \u06a9\u0648 \u0642\u0627\u0646\u0648\u0646\u06cc \u06af\u0631\u0641\u062a \u0633\u06d2 \u0628\u0627\u0644\u06a9\u0644 \u0622\u0632\u0627\u062f \u06a9\u0631\u062f\u06cc\u0627\u062c\u0627\u0626\u06d2 \u06a9\u06c1 \u062c\u062a\u0646\u0627 \u0686\u0627\u06c1\u06d2\u060c \u062c\u06c1\u0627\u06ba \u0686\u0627\u06c1\u06d2\u060c \u062c\u0628 \u0686\u0627\u06c1\u06d2 \u0641\u0633\u0627\u062f \u0628\u0631\u067e\u0627 \u06a9\u0631\u06d2\u060c \u062c\u0633 \u0642\u062f\u0631 \u0686\u0627\u06c1\u06d2 \u0638\u0644\u0645 \u0648\u0633\u062a\u0645 \u06a9\u06d2 \u067e\u06c1\u0627\u0691 \u062a\u0648\u0691\u06d2\u060c \u062c\u0633 \u06a9\u0648 \u0686\u0627\u06c1\u06d2 \u0627\u0648\u0631 \u062c\u0628 \u0686\u0627\u06c1\u06d2 \u0628\u06d2 \u0622\u0628\u0631\u0648 \u06a9\u0631\u06a9\u06d2 \u0627\u0633 \u06a9\u06cc \u0639\u0632\u062a \u0648\u0622\u0628\u0631\u0648 \u06a9\u0627 \u062c\u0646\u0627\u0632\u06c1 \u0646\u06a9\u0627\u0644 \u062f\u06d2 \u0627\u0648\u0631 \u0627\u0646 \u062a\u0645\u0627\u0645 \u06a9\u06d2 \u0628\u0627\u0648\u062c\u0648\u062f \u0627\u0633 \u06a9\u06cc \u062c\u0627\u0646 \u0645\u062d\u062a\u0631\u0645 \u06c1\u06cc \u0631\u06c1\u06d2\u061b \u0628\u0644\u06a9\u06c1 \u0627\u0635\u0644 \u0636\u0631\u0648\u0631\u062a \u06cc\u06c1 \u062a\u06be\u06cc \u06a9\u06c1 \u062f\u0646\u06cc\u0627\u0645\u06cc\u06ba \u0627\u0645\u0646 \u0648\u0627\u0645\u0627\u0646 \u06a9\u06cc \u062e\u0648\u0634 \u06af\u0648\u0627\u0631 \u0641\u0636\u0627 \u0642\u0627\u0626\u0645 \u06a9\u06cc \u062c\u0627\u0626\u06d2 \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0627\u06cc\u0633\u0627 \u0645\u0646\u0638\u0645 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u062a\u06cc\u0627\u0631 \u06a9\u06cc\u0627\u062c\u0627\u0626\u06d2\u060c \u062c\u0633 \u06a9\u06d2 \u062a\u062d\u062a \u06c1\u0631 \u0641\u0631\u062f \u0627\u067e\u0646\u06cc \u062d\u062f\u0648\u062f \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f \u0631\u06c1\u06d2 \u0627\u0648\u0631 \u06a9\u0648\u0626\u06cc \u0634\u062e\u0635 \u0627\u067e\u0646\u06d2 \u062d\u062f\u0648\u062f \u0633\u06d2 \u062a\u062c\u0627\u0648\u0632 \u0646\u06c1 \u06a9\u0631\u06d2\u060c \u0627\u0633 \u063a\u0631\u0636 \u06a9\u06d2 \u0644\u06cc\u06d2 \ufd3f\u0627\u0650\u0644\u0627\u064e\u0651 \u0628\u0650\u0627\u0644\u0652\u062d\u064e\u0642\u0650\u0651\ufd3e \u06a9\u06cc \u0645\u062d\u0627\u0641\u0638 \u0642\u0648\u062a \u062f\u0631\u06a9\u0627\u0631 \u062a\u06be\u06cc \u0648\u0631\u0646\u06c1 \u0627\u0645\u0646 \u06a9\u06cc \u062c\u06af\u06c1 \u0628\u062f\u0627\u0645\u0646\u06cc \u06c1\u0648\u062a\u06cc\u06d4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u0642\u062a\u0644 \u062d\u0642 \u0627\u0648\u0631 \u0642\u062a\u0644 \u0646\u0627\u062d\u0642 \u0627\u0648\u0631 \u0642\u062a\u0644 \u0628\u063a\u06cc\u0631 \u0627\u0644\u062d\u0642 \u06a9\u0627 \u0641\u0631\u0642<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0642\u062a\u0644 \u0646\u0627\u062d\u0642 \u06a9\u06cc \u0627\u06cc\u0633\u06cc \u0633\u062e\u062a \u0645\u0645\u0627\u0646\u0639\u062a \u0627\u0648\u0631 \u0642\u062a\u0644 \u062d\u0642 \u06a9\u06cc \u0627\u06cc\u0633\u06cc \u0633\u062e\u062a \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u06a9\u06d2 \u0634\u0631\u06cc\u0639\u062a \u0650 \u0627\u0633\u0644\u0627\u0645\u06cc\u06c1 \u0646\u06d2 \u0627\u0641\u0631\u0627\u0637 \u0648\u062a\u0641\u0631\u06cc\u0637 \u06a9\u06cc \u0631\u0627\u06c1\u0648\u06ba \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0639\u062f\u0644 \u0648\u062a\u0648\u0633\u0637 \u06a9\u06cc \u0633\u06cc\u062f\u06be\u06cc \u0631\u0627\u06c1 \u06a9\u06cc \u0637\u0631\u0641 \u06c1\u0645\u0627\u0631\u06cc \u0631\u0627\u06c1 \u0646\u0645\u0627\u0626\u06cc \u06a9\u06cc \u06c1\u06d2\u060c \u0627\u06cc\u06a9 \u0637\u0631\u0641 \u0648\u06c1 \u0645\u064f\u0633\u0631\u0641 \u0627\u0648\u0631 \u062d\u062f \u0633\u06d2 \u062a\u062c\u0627\u0648\u0632 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u0627 \u06af\u0631\u0648\u06c1 \u06c1\u06d2\u060c \u062c\u0648 \u0627\u0646\u0633\u0627\u0646\u06cc \u062c\u0627\u0646 \u06a9\u06cc \u06a9\u0648\u0626\u06cc \u0642\u062f\u0631 \u0648\u0642\u06cc\u0645\u062a \u0646\u06c1\u06cc\u06ba \u0633\u0645\u062c\u06be\u062a\u0627 \u0627\u0648\u0631 \u062f\u0648\u0633\u0631\u06cc \u0637\u0631\u0641 \u0648\u06c1 \u063a\u0644\u0637 \u0641\u06c1\u0645 \u0627\u0648\u0631 \u06a9\u0648\u0631\u0686\u0634\u0645 \u06af\u0631\u0648\u06c1 \u06c1\u06d2\u060c \u062c\u0648 \u0627\u0646\u0633\u0627\u0646\u06cc \u062e\u0648\u0646 \u06a9\u06cc \u062f\u0627\u0626\u0645\u06cc \u062d\u0631\u0645\u062a \u06a9\u0627 \u0642\u0627\u0626\u0644 \u06c1\u06d2 \u0627\u0648\u0631 \u06a9\u0633\u06cc \u0635\u0648\u0631\u062a \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0627\u0633\u06d2 \u0628\u06c1\u0627\u0646\u0627 \u062c\u0627\u0626\u0632 \u0646\u06c1\u06cc\u06ba \u06af\u0631\u062f\u0627\u0646\u062a\u0627\u060c\u0627\u0633\u0644\u0627\u0645 \u0646\u06d2 \u0627\u0646 \u062f\u0648\u0646\u0648\u06ba \u063a\u0644\u0637 \u062e\u06cc\u0627\u0644\u0648\u06ba \u06a9\u06cc \u062a\u0631\u062f\u06cc\u062f \u06a9\u0631\u062f\u06cc \u0627\u0648\u0631 \u0627\u0633 \u0646\u06d2 \u06cc\u06c1 \u062a\u0639\u0644\u06cc\u0645 \u062f\u06cc \u06a9\u06c1 \u0627\u0646\u0633\u0627\u0646\u06cc \u0646\u0641\u0633 \u06a9\u06cc \u062d\u0631\u0645\u062a \u0646\u06c1 \u062a\u0648 \u0627\u0628\u062f\u06cc \u0627\u0648\u0631 \u062f\u0627\u0626\u0645\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0646\u06c1 \u0627\u0633 \u06a9\u06cc \u0642\u062f\u0631 \u0648\u0642\u06cc\u0645\u062a \u0627\u0633 \u0642\u062f\u0631 \u0627\u0631\u0632\u0627\u06ba \u0627\u0648\u0631 \u0633\u0633\u062a\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0646\u0641\u0633\u0627\u0646\u06cc \u062c\u0630\u0628\u0627\u062a \u06a9\u06cc \u062a\u0633\u06a9\u06cc\u0646 \u06a9\u06cc \u062e\u0627\u0637\u0631 \u0627\u0633\u06d2 \u06c1\u0644\u0627\u06a9 \u06a9\u0631\u062f\u06cc\u0646\u0627 \u062c\u0627\u0626\u0632\u06c1\u0648\u061b \u0645\u06af\u0631 \u062c\u0628 \u0648\u06c1 \u0633\u0631\u06a9\u0634\u06cc \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06a9\u06d2 \u062d\u0642 \u067e\u0631 \u062f\u0633\u062a \u062f\u0631\u0627\u0632\u06cc \u06a9\u0631\u062a\u0627\u06c1\u06d2\u060c \u062a\u0648 \u0627\u067e\u0646\u06d2 \u062e\u0648\u0646 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u06a9\u0648 \u06a9\u06be\u0648\u062f\u06cc\u062a\u0627 \u06c1\u06d2\u060c \u067e\u06be\u0631 \u0627\u0633 \u06a9\u06d2 \u062e\u0648\u0646 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0627\u062a\u0646\u06cc \u0628\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u0631\u06c1 \u062c\u0627\u062a\u06cc \u062c\u062a\u0646\u06cc \u06a9\u06c1 \u067e\u0627\u0646\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u06d4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u062c\u0646\u06af \u0627\u06cc\u06a9 \u0627\u062e\u0644\u0627\u0642\u06cc \u0641\u0631\u06cc\u0636\u06c1<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u062c\u0628 \u06a9\u0648\u0626\u06cc \u062c\u0645\u0627\u0639\u062a \u0633\u0631\u06a9\u0634\u06cc \u067e\u0631 \u0627\u062a\u0631 \u0622\u062a\u06cc \u06c1\u06d2\u060c \u062a\u0648 \u0648\u06c1 \u06a9\u0648\u0626\u06cc \u0627\u06cc\u06a9 \u0641\u062a\u0646\u06c1 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627\u060c \u062c\u0648 \u0648\u06c1 \u0628\u0631\u067e\u0627 \u06a9\u0631\u062a\u06cc \u06c1\u0648\u061b \u0628\u0644\u06a9\u06c1 \u0627\u0646 \u0645\u06cc\u06ba \u0637\u0631\u062d \u0637\u0631\u062d \u06a9\u06d2 \u0634\u06cc\u0637\u0627\u0646 \u0635\u0641\u062a \u0627\u0646\u0633\u0627\u0646 \u0628\u06be\u06cc \u0634\u0627\u0645\u0644 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u06c1\u0632\u0627\u0631\u0648\u06ba \u0637\u0631\u062d \u06a9\u06d2 \u0641\u062a\u0646\u06d2 \u0627\u0646 \u06a9\u06cc \u0628\u062f\u0648\u0644\u062a \u0648\u062c\u0648\u062f \u067e\u0630\u06cc\u0631 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0627\u0646 \u0634\u06cc\u0637\u0627\u0646\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06d2 \u062a\u0648 \u0628\u0639\u0636 \u0637\u0645\u0639 \u0648\u062d\u0631\u0635 \u06a9\u06d2 \u067e\u062c\u0627\u0631\u06cc \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba \u062c\u0648 \u063a\u0631\u06cc\u0628 \u0642\u0648\u0645\u0648\u06ba \u067e\u0631\u0688\u0627\u06a9\u06c1 \u0688\u0627\u0644\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0627\u0646 \u06a9\u06d2 \u062e\u0648\u0646 \u067e\u0633\u06cc\u0646\u06c1 \u0633\u06d2 \u06a9\u0645\u0627\u0626\u06d2 \u06c1\u0648\u0626\u06d2 \u0631\u0648\u067e\u06cc\u0648\u06ba \u067e\u06cc\u0633\u0648\u06ba \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0639\u06cc\u0627\u0631\u0627\u0646\u06c1 \u0686\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0644\u0648\u0679\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u067e\u06be\u0631 \u0627\u067e\u0646\u06cc \u062a\u062c\u0648\u0631\u06cc\u0627\u06ba \u0628\u06be\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0639\u062f\u0644 \u0648\u0627\u0646\u0635\u0627\u0641 \u06a9\u0648 \u0645\u0679\u0627\u06a9\u0631 \u062c\u0648\u0631 \u0648\u062c\u0641\u0627 \u06a9\u06d2 \u0639\u0644\u064e\u0645 \u06a9\u0648 \u0628\u0644\u0646\u062f \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0627\u0646 \u06a9\u06d2 \u0646\u0627\u067e\u0627\u06a9 \u0627\u062b\u0631 \u0633\u06d2 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06d2 \u0627\u062e\u0644\u0627\u0642 \u062a\u0628\u0627\u06c1 \u0648\u0628\u0631\u0628\u0627\u062f \u06c1\u0648\u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u0627\u06cc\u0633\u06cc \u062d\u0627\u0644\u062a \u0645\u06cc\u06ba \u062c\u0646\u06af \u062c\u0627\u0626\u0632 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba\u061b \u0628\u0644\u06a9\u06c1 \u0641\u0631\u0636 \u06c1\u0648\u062c\u0627\u062a\u06cc \u06c1\u06d2\u060c \u0627\u0633 \u0648\u0642\u062a \u0627\u0646\u0633\u0627\u0646\u06cc\u062a \u06a9\u06cc \u0633\u0628 \u0633\u06d2 \u0628\u0691\u06cc \u062e\u062f\u0645\u062a \u06cc\u06c1\u06cc \u06c1\u0648\u062a\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0627\u0646 \u0638\u0627\u0644\u0645 \u0628\u06be\u06cc\u0691\u06cc\u0648\u06ba \u06a9\u06d2 \u062e\u0648\u0646 \u0633\u06d2 \u0635\u0641\u062d\u06c1\u0674 \u06c1\u0633\u062a\u06cc \u06a9\u06d2 \u0633\u06cc\u0646\u06d2 \u06a9\u0648 \u0633\u0631\u062e \u06a9\u0631\u062f\u06cc\u0627 \u062c\u0627\u0626\u06d2 \u0627\u0648\u0631 \u0627\u0646 \u0645\u0641\u0633\u062f\u0648\u06ba \u06a9\u06d2 \u0634\u0631 \u0633\u06d2 \u0627\u0644\u0644\u06c1 \u06a9\u06d2 \u0645\u0638\u0644\u0648\u0645 \u0648\u0628\u06d2 \u06a9\u0633 \u0628\u0646\u062f\u0648\u06ba \u06a9\u0648 \u0646\u062c\u0627\u062a \u062f\u0644\u0627\u0626\u06cc \u062c\u0627\u0626\u06d2\u060c \u062c\u0648 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06cc \u0627\u0645\u062a \u0628\u0646 \u06a9\u0631 \u0627\u0648\u0644\u0627\u062f\u0650 \u0622\u062f\u0645 \u067e\u0631 \u0627\u062e\u0644\u0627\u0642\u06cc\u060c \u0631\u0648\u062d\u0627\u0646\u06cc \u0627\u0648\u0631 \u0645\u0627\u062f\u06cc \u062a\u0628\u0627\u06c1\u06cc \u06a9\u06cc \u0645\u0635\u06cc\u0628\u062a\u06cc\u06ba \u0646\u0627\u0632\u0644 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0648\u06c1 \u0644\u0648\u06af \u0627\u0646\u0633\u0627\u0646 \u0646\u06c1\u06cc\u06ba\u061b \u0628\u0644\u06a9\u06c1 \u0627\u0646\u0633\u0627\u0646\u0648\u06ba \u06a9\u06cc \u0634\u06a9\u0644 \u0648\u0635\u0648\u0631\u062a \u0645\u06cc\u06ba \u062f\u0631\u0646\u062f\u06d2 \u0627\u0648\u0631\u0627\u0646\u0633\u0627\u0646\u06cc\u062a \u06a9\u06d2 \u062d\u0642\u06cc\u0642\u06cc \u062f\u0634\u0645\u0646 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062c\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u0635\u0644\u06cc \u06c1\u0645\u062f\u0631\u062f\u06cc \u06cc\u06c1\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0627\u0646 \u06a9\u0648 \u0635\u0641\u062d\u06c1\u0674 \u06c1\u0633\u062a\u06cc \u0633\u06d2 \u062d\u0631\u0641\u0650 \u063a\u0644\u0637 \u06a9\u06cc \u0637\u0631\u062d \u0645\u0679\u0627\u062f\u06cc\u0627 \u062c\u0627\u0626\u06d2\u060c \u0627\u06cc\u0633\u06d2 \u0648\u0642\u062a \u0645\u06cc\u06ba \u06c1\u0631 \u0633\u0686\u06d2\u060c \u0628\u06c1\u06cc \u062e\u0648\u0627\u06c1 \u0627\u0646\u0633\u0627\u0646\u06cc\u062a \u06a9\u0627 \u0627\u0648\u0644\u06cc\u0646 \u0641\u0631\u0636 \u06c1\u0648\u062c\u0627\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u0633\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062a\u0644\u0648\u0627\u0631 \u0627\u0679\u06be\u0627\u0626\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u0648\u0642\u062a \u062a\u06a9 \u0622\u0631\u0627\u0645 \u0646\u06c1 \u06a9\u0631\u06d2\u060c \u062c\u0628 \u062a\u06a9 \u06a9\u06c1 \u062e\u062f\u0627 \u06a9\u06cc \u0645\u062e\u0644\u0648\u0642 \u06a9\u0648 \u0627\u0633 \u06a9\u06d2 \u06a9\u06be\u0648\u0626\u06d2 \u06c1\u0648\u0626\u06d2 \u062d\u0642\u0648\u0642 \u0648\u0627\u067e\u0633 \u0646\u06c1 \u0645\u0644 \u062c\u0627\u0626\u06cc\u06ba\u06d4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u062c\u0646\u06af \u06a9\u06cc \u062d\u06a9\u0645\u062a \u0648\u0645\u0635\u0644\u062d\u062a<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u062c\u0646\u06af \u06a9\u06cc \u0645\u0635\u0644\u062d\u062a \u06a9\u0648 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u062d\u06a9\u06cc\u0645\u0627\u0646\u06c1 \u0627\u0646\u062f\u0627\u0632 \u0645\u06cc\u06ba \u0628\u06cc\u0627\u0646 \u0641\u0631\u0645\u0627\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 : \ufd3f\u0648\u064e\u0644\u064e\u0648\u0652\u0644\u0627\u064e \u062f\u064e\u0641\u064e\u0639\u064f \u0627\u0644\u0644\u06c1\u0650 \u0627\u0644\u0646\u064e\u0651\u0627\u0633\u064e \u0628\u064e\u0639\u0652\u0636\u064e\u06be\u064f\u0645\u0652 \u0628\u0650\u0628\u064e\u0639\u0652\u0636\u064d \u0644\u064e\u0651\u06be\u064f\u062f\u0650\u0651\u0645\u064e\u062a\u0652 \u0635\u064e\u0648\u064e\u0627\u0645\u0650\u0639\u064f \u0648\u064e\u0628\u0650\u06cc\u064e\u0639\u064c \u0648\u064e\u0651 \u0635\u064e\u0644\u064e\u0648\u0670\u0627\u062a\u064c \u0648\u064e\u0651 \u0645\u064e\u0633\u0670\u062c\u0650\u062f\u064f \u06cc\u064f\u0630\u0652\u06a9\u064e\u0631\u064f \u0641\u0650\u06cc\u0652\u06be\u064e\u0627 \u0627\u0633\u0652\u0645\u064f \u0627\u0644\u0644\u06c1\u0650 \u06a9\u064e\u062b\u0650\u06cc\u0652\u0631\u0627\u064b\ufd3e (\u0627\u0644\u062d\u062c:\u06f4\u06f0): \u201d\u0627\u06af\u0631 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u0631\u06d2 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06c1 \u062f\u0641\u0639 \u0646\u06c1 \u06a9\u0631\u062a\u0627\u060c \u062a\u0648 \u0635\u0648\u0645\u0639\u06d2 \u0627\u0648\u0631 \u06af\u0631\u062c\u06d2 \u0627\u0648\u0631 \u0645\u0639\u0628\u062f \u0627\u0648\u0631 \u0645\u0633\u062c\u062f\u06cc\u06ba\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0627\u0644\u0644\u06c1 \u06a9\u0627 \u0630\u06a9\u0631 \u06a9\u062b\u0631\u062a \u0633\u06d2 \u06a9\u06cc\u0627\u062c\u0627\u062a\u0627 \u06c1\u06d2\u060c \u0645\u0633\u0645\u0627\u0631 \u06a9\u0631\u062f\u06cc\u06d2 \u062c\u0627\u062a\u06d2\u06d4\u201c<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u062c\u0646\u06af \u06a9\u06cc \u0627\u0633\u06cc \u0645\u0635\u0644\u062d\u062a \u06a9\u0648 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u0631\u06cc \u062c\u06af\u06c1 \u06cc\u0648\u06ba \u0628\u06cc\u0627\u0646 \u0641\u0631\u0645\u0627\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1: \ufd3f\u0648\u064e\u0644\u064e\u0648\u0652\u0644\u0627\u064e \u062f\u064e\u0641\u064e\u0639\u064f \u0627\u0644\u0644\u06c1\u0650 \u0627\u0644\u0646\u064e\u0651\u0627\u0633\u064e \u0628\u064e\u0639\u0652\u0636\u064e\u06be\u064f\u0645\u0652 \u0628\u0650\u0628\u064e\u0639\u0652\u0636\u064d \u0644\u064e\u0651\u0641\u064e\u0633\u064e\u062f\u064e\u062a\u0650 \u0627\u0644\u0652\u0627\u064e\u0631\u0652\u0636\u064f \u0648\u064e\u0644\u0670\u06a9\u0650\u0646\u064e\u0651 \u0627\u0644\u0644\u06c1\u064e \u0630\u064f\u0648\u0652\u0641\u064e\u0636\u0652\u0644\u064d \u0639\u064e\u0644\u064e\u06cc \u0627\u0644\u0652\u0639\u0670\u0644\u064e\u0645\u0650\u06cc\u0652\u0646\u064e\ufd3e (\u0627\u0644\u0628\u0642\u0631\u06c1:\u06f2\u06f5\u06f1) \u062a\u0631\u062c\u0645\u06c1: \u201d\u0627\u06af\u0631 \u0627\u0644\u0644\u06c1 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u0631\u06d2 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06c1 \u062f\u0641\u0639 \u0646\u06c1 \u06a9\u0631\u062a\u0627\u060c \u062a\u0648 \u0632\u0645\u06cc\u0646 \u0641\u0633\u0627\u062f \u0633\u06d2 \u0628\u06be\u0631 \u062c\u0627\u062a\u06cc\u061b \u0645\u06af\u0631 \u062f\u0646\u06cc\u0627 \u0648\u0627\u0644\u0648\u06ba \u067e\u0631 \u0627\u0644\u0644\u06c1 \u06a9\u0627 \u0628\u0691\u0627 \u0641\u0636\u0644 \u06c1\u06d2\u06d4\u201c (\u06a9\u06c1 \u0648\u06c1 \u062f\u0641\u0639\u0650 \u0641\u0633\u0627\u062f \u06a9\u0627 \u0627\u0646\u062a\u0638\u0627\u0645 \u06a9\u0631\u062a\u0627 \u0631\u06c1\u062a\u0627 \u06c1\u06d2)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u062c\u06c1\u0627\u062f \u0641\u06cc \u0633\u0628\u06cc\u0644 \u0627\u0644\u0644\u06c1<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u06cc\u06c1\u06cc \u0641\u0633\u0627\u062f \u0648\u0628\u062f\u0627\u0645\u0646\u06cc \u0638\u0644\u0645 \u0648\u062c\u0628\u0631 \u06a9\u06cc \u062c\u0646\u06af \u06c1\u06d2\u060c \u062c\u0633 \u06a9\u0648 \u062f\u0641\u0639 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0646\u06cc\u06a9 \u0628\u0646\u062f\u0648\u06ba \u06a9\u0648 \u062a\u0644\u0648\u0627\u0631 \u0627\u0679\u06be\u0627\u0646\u06d2 \u06a9\u0627 \u062d\u06a9\u0645 \u062f\u06cc\u0627 \u06c1\u06d2\u061b \u0686\u0646\u0627\u0646\u0686\u06c1 \u0627\u0631\u0634\u0627\u062f \u0628\u0627\u0631\u06cc \u062a\u0639\u0627\u0644\u06cc\u0670 \u06c1\u06d2: \ufd3f\u0627\u064f\u0630\u0650\u0646\u064e \u0644\u0650\u0644\u064e\u0651\u0630\u0650\u06cc\u0652\u0646\u064e \u06cc\u064f\u0642\u0670\u062a\u0650\u0644\u064f\u0648\u0652\u0646\u064e \u0628\u0650\u0627\u064e\u0646\u064e\u0651\u06be\u064f\u0645\u0652 \u0638\u064f\u0644\u0650\u0645\u064f\u0648\u0652\u0627 \u0648\u064e\u0627\u0650\u0646\u064e\u0651 \u0627\u0644\u0644\u06c1\u064e \u0639\u064e\u0644\u0670\u06cc \u0646\u064e\u0635\u0652\u0631\u0650\u06be\u0650\u0645\u0652 \u0644\u064e\u0642\u064e\u062f\u0650\u06cc\u0652\u0631\u064f o \u0627\u0644\u064e\u0651\u0630\u0650\u06cc\u0652\u0646\u064e \u0627\u064f\u062e\u0652\u0631\u0650\u062c\u064f\u0648\u0652\u0627 \u0645\u0650\u0646\u0652 \u062f\u0650\u06cc\u064e\u0627\u0631\u0650\u06be\u0650\u0645\u0652 \u0628\u0650\u063a\u064e\u06cc\u0652\u0631\u0650 \u062d\u064e\u0642\u064d\u0651 \u0627\u0650\u0644\u0627\u064e\u0651 \u0627\u064e\u0646\u0652 \u06cc\u064e\u0651\u0642\u064f\u0648\u0652\u0644\u064f\u0648\u0652\u0627 \u0631\u064e\u0628\u064f\u0651\u0646\u064e\u0627 \u0627\u0644\u0644\u06c1\u064f\ufd3e (\u0627\u0644\u062d\u062c:\u06f3\u06f9-\u06f4\u06f0) \u201d\u062c\u0646 \u0644\u0648\u06af\u0648\u06ba \u0633\u06d2 \u062c\u0646\u06af \u06a9\u06cc \u062c\u0627\u0631\u06c1\u06cc \u06c1\u06d2\u060c \u0627\u0646\u06be\u06cc\u06ba \u0644\u0691\u0646\u06d2 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u062f\u06cc \u062c\u0627\u062a\u06cc \u06c1\u06d2\u061b \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0646 \u067e\u0631 \u0638\u0644\u0645 \u06c1\u0648\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0644\u0644\u06c1 \u0627\u0646 \u06a9\u06cc \u0645\u062f\u062f \u067e\u0631 \u06cc\u0642\u06cc\u0646\u0627 \u0642\u062f\u0631\u062a \u0631\u06a9\u06be\u062a\u0627 \u06c1\u06d2\u060c \u06cc\u06c1 \u0648\u06c1 \u0644\u0648\u06af \u06c1\u06cc\u06ba\u060c \u062c\u0648 \u0627\u067e\u0646\u06d2 \u06af\u06be\u0631\u0648\u06ba \u0633\u06d2 \u0628\u06d2 \u0642\u0635\u0648\u0631 \u0646\u06a9\u0627\u0644\u06d2 \u06af\u0626\u06d2\u060c \u0627\u0646 \u06a9\u0627 \u0642\u0635\u0648\u0631 \u0635\u0631\u0641 \u06cc\u06c1 \u062a\u06be\u0627 \u06a9\u06c1 \u06cc\u06c1 \u0627\u0644\u0644\u06c1 \u06a9\u0648 \u0627\u067e\u0646\u0627 \u067e\u0631\u0648\u0631\u062f\u06af\u0627\u0631 \u06a9\u06c1\u062a\u06d2 \u062a\u06be\u06d2\u201c \u0627\u0633 \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u062c\u0646 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062c\u0646\u06af \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u062d\u06a9\u0645 \u062f\u06cc\u0627 \u062c\u0627\u0631\u06c1\u0627 \u06c1\u06d2\u060c \u0627\u0646 \u06a9\u0627 \u062c\u0631\u0645 \u06cc\u06c1 \u0646\u06c1\u06cc\u06ba \u0628\u06cc\u0627\u0646 \u06a9\u06cc\u0627 \u062c\u0627\u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u0631\u06d2 \u0645\u0630\u06c1\u0628 \u06a9\u06d2 \u067e\u06cc\u0631\u0648\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u061b \u0628\u0644\u06a9\u06c1 \u0627\u0646 \u06a9\u0627 \u062c\u0631\u0645 \u0648\u0627\u0636\u062d \u0627\u0646\u062f\u0627\u0632 \u0645\u06cc\u06ba \u06cc\u06c1 \u0628\u06cc\u0627\u0646 \u06a9\u06cc\u0627\u062c\u0627\u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0638\u0644\u0645 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0628\u06d2 \u0642\u0635\u0648\u0631 \u0627\u0646 \u06a9\u06d2 \u06af\u06be\u0631\u0648\u06ba \u0633\u06d2 \u0646\u06a9\u0627\u0644\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0627\u06cc\u0633\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0635\u0631\u0641 \u0645\u062f\u0627\u0641\u0639\u062a\u06cc \u062c\u0646\u06af \u06a9\u0627 \u062d\u06a9\u0645 \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u0627\u06af\u06cc\u0627\u061b \u0628\u0644\u06a9\u06c1 \u062f\u0648\u0633\u0631\u06d2 \u0645\u0638\u0644\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0627\u0639\u0627\u0646\u062a \u06a9\u0627 \u0628\u06be\u06cc \u062d\u06a9\u0645 \u062f\u06cc\u0627\u06af\u06cc\u0627 \u0627\u0648\u0631 \u062a\u0627\u06a9\u06cc\u062f \u06a9\u06cc \u06af\u0626\u06cc \u06a9\u06c1 \u06a9\u0645\u0632\u0648\u0631 \u0648 \u0628\u06d2 \u0628\u0633 \u0644\u0648\u06af\u0648 \u06a9\u0648 \u0638\u0627\u0644\u0645\u0648\u06ba \u06a9\u06d2 \u067e\u0646\u062c\u0648\u06ba \u0633\u06d2 \u0686\u06be\u0691\u0627\u0624\u06d4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u062d\u0642 \u0648\u0628\u0627\u0637\u0644 \u06a9\u06cc \u062d\u062f \u0628\u0646\u062f\u06cc<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u067e\u06be\u0631 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0646\u06d2 \u062c\u0646\u06af \u06a9\u06cc \u0627\u06c1\u0645\u06cc\u062a \u0648\u0636\u0631\u0648\u0631\u062a \u06a9\u0648 \u0638\u0627\u06c1\u0631 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u06cc\u06c1 \u062a\u0635\u0631\u06cc\u062d \u0628\u06be\u06cc \u0641\u0631\u0645\u0627\u062f\u06cc : \ufd3f\u0627\u064e\u0644\u064e\u0651\u0630\u0650\u06cc\u0652\u0646\u064e \u0622\u0645\u064e\u0646\u064f\u0648\u0652\u0627 \u06cc\u064f\u0642\u064e\u0627\u062a\u0650\u0644\u064f\u0648\u0652\u0646\u064e \u0641\u0650\u06cc\u0652 \u0633\u064e\u0628\u0650\u06cc\u0652\u0644\u0650 \u0627\u0644\u0644\u06c1\u0650 \u062c \u0648\u064e\u0627\u0644\u064e\u0651\u0630\u0650\u06cc\u0652\u0646\u064e \u06a9\u064e\u0641\u064e\u0631\u064f\u0648\u0652\u0627 \u06cc\u064f\u0642\u064e\u0627\u062a\u0650\u0644\u064f\u0648\u0652\u0646\u064e \u0641\u0650\u06cc\u0652 \u0633\u064e\u0628\u0650\u06cc\u0652\u0644\u0650 \u0627\u0644\u0637\u064e\u0651\u0627\u063a\u064f\u0648\u0652\u062a\u0650 \u0641\u064e\u0642\u064e\u0627\u062a\u0650\u0644\u064f\u0648\u0652\u0622 \u0627\u064e\u0648\u0652\u0644\u0650\u06cc\u064e\u0622\u0621\u064e \u0627\u0644\u0634\u064e\u0651\u06cc\u0652\u0637\u0670\u0646\u0650 \u062c \u0627\u0650\u0646\u064e\u0651 \u06a9\u064e\u06cc\u0652\u062f\u064e \u0627\u0644\u0634\u064e\u0651\u06cc\u0652\u0637\u0670\u0646\u0650 \u06a9\u064e\u0627\u0646\u064e \u0636\u064e\u0639\u0650\u06cc\u0652\u0641\u0627\u064b\ufd3e (\u0627\u0644\u0646\u0633\u0627\u0621:\u06f7\u06f6) \u201d\u062c\u0648 \u0644\u0648\u06af \u0627\u06cc\u0645\u0627\u0646 \u062f\u0627\u0631 \u06c1\u06cc\u06ba\u060c \u0648\u06c1 \u0627\u0644\u0644\u06c1 \u06a9\u06cc \u0631\u0627\u06c1 \u0645\u06cc\u06ba \u062c\u0646\u06af \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u062c\u0648 \u06a9\u0627\u0641\u0631 \u0648\u0633\u0631\u06a9\u0634 \u06c1\u06cc\u06ba \u0648\u06c1 \u0638\u0644\u0645 \u0648\u0633\u0631\u06a9\u0634\u06cc \u06a9\u06cc \u062e\u0627\u0637\u0631 \u0644\u0691\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u067e\u0633 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06d2 \u062f\u0648\u0633\u062a\u0648\u06ba \u0633\u06d2 \u0644\u0691\u0648\u06a9\u06c1 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06cc \u062a\u062f\u0628\u06cc\u0631 \u0644\u0686\u0631 \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u201c \u06cc\u06c1 \u0627\u06cc\u06a9 \u0642\u0648\u0644\u0650 \u0641\u06cc\u0635\u0644 \u06c1\u06d2\u060c \u062c\u0633 \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u062d\u0642 \u0648\u0628\u0627\u0637\u0644 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062e\u0637 \u06a9\u06be\u06cc\u0646\u0686 \u062f\u06cc \u06af\u0626\u06cc \u06c1\u06d2 \u06a9\u06c1 \u062c\u0648 \u0644\u0648\u06af \u0638\u0644\u0645 \u0648\u0633\u0631\u06a9\u0634\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u062c\u0646\u06af \u06a9\u0631\u06cc\u06ba \u06af\u06d2\u060c \u0648\u06c1 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06d2 \u062d\u0627\u0645\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u062c\u0648\u0644\u0648\u06af \u0638\u0644\u0645 \u06a9\u0648 \u0645\u0679\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062c\u0646\u06af \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0648\u06c1 \u0631\u0627\u06c1\u0650 \u062e\u062f\u0627 \u06a9\u06d2 \u0645\u062c\u0627\u06c1\u062f \u06c1\u06cc\u06ba\u06d4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u062c\u06c1\u0627\u062f \u0641\u06cc \u0633\u0628\u06cc\u0644 \u0627\u0644\u0644\u06c1 \u06a9\u06cc \u0641\u0636\u06cc\u0644\u062a<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u06cc\u06c1\u06cc \u0648\u06c1 \u062c\u06c1\u0627\u062f \u06c1\u06d2\u060c \u062c\u0633 \u06a9\u06cc \u0641\u0636\u06cc\u0644\u062a \u0633\u06d2 \u0642\u0631\u0622\u0646 \u0648\u062d\u062f\u06cc\u062b \u06a9\u06d2 \u0635\u0641\u062d\u0627\u062a \u0628\u06be\u0631\u06d2 \u067e\u064f\u0631\u06d2 \u06c1\u06cc\u06ba\u060c \u06cc\u06c1\u06cc \u0648\u06c1 \u062d\u0642 \u067e\u0631\u0633\u062a\u06cc \u06a9\u06cc \u062c\u0646\u06af \u06c1\u06d2\u060c \u062c\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0631\u0627\u062a \u06a9\u0627 \u062c\u0627\u06af\u0646\u0627 \u06c1\u0632\u0627\u0631 \u0631\u0627\u062a\u06cc\u06ba \u062c\u0627\u06af \u06a9\u0631 \u0639\u0628\u0627\u062f\u062a \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0628\u0691\u06be \u06a9\u0631 \u06c1\u06d2\u060c \u062c\u0633 \u0631\u0627\u06c1 \u0645\u06cc\u06ba \u063a\u0628\u0627\u0631 \u0622\u0644\u0648\u062f \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0642\u062f\u0645\u0648\u06ba \u0633\u06d2 \u0648\u0639\u062f\u06c1 \u06a9\u06cc\u0627 \u06af\u06cc\u0627\u06c1\u06d2 \u06a9\u06c1 \u0627\u0646 \u06a9\u0648 \u062c\u06c1\u0646\u0645 \u06a9\u06cc \u0622\u06af \u06a9\u06cc \u0637\u0631\u0641 \u0646\u06c1\u06cc\u06ba \u06af\u06be\u0633\u06cc\u0679\u0627 \u062c\u0627\u0626\u06d2 \u06af\u0627\u06d4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u062c\u06c1\u0627\u062f \u06a9\u06cc \u0641\u0636\u06cc\u0644\u062a \u06a9\u06cc \u0648\u062c\u06c1<\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u062c\u06c1\u0627\u062f \u0641\u06cc \u0633\u0628\u06cc\u0644 \u0627\u0644\u0644\u06c1 \u06a9\u06cc \u0627\u062a\u0646\u06cc \u0641\u0636\u06cc\u0644\u062a \u0627\u0648\u0631 \u062a\u0639\u0631\u06cc\u0641 \u06a9\u0633 \u0644\u06cc\u06d2 \u06c1\u06d2\u061f \u0627\u0633 \u062c\u06c1\u0627\u062f \u0633\u06d2 \u062f\u0646\u06cc\u0627 \u06a9\u06cc \u062f\u0648\u0644\u062a \u0627\u0648\u0631 \u0645\u0644\u06a9 \u06af\u06cc\u0631\u06cc \u0645\u0642\u0635\u0648\u062f \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u060c \u062a\u0648 \u0622\u062e\u0631 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0627\u0633 \u06a9\u06d2 \u0639\u0648\u0636 \u0628\u0691\u06d2 \u0628\u0691\u06d2 \u062f\u0631\u062c\u06d2 \u06a9\u06cc\u0648\u06ba \u062f\u06d2 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u061f \u0627\u0633 \u0644\u06cc\u06d2 \u06a9\u06c1 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc\u0670 \u0646\u06c1\u06cc\u06ba \u0686\u0627\u06c1\u062a\u0627 \u06a9\u06c1 \u0627\u0633 \u06a9\u06cc \u0632\u0645\u06cc\u0646 \u067e\u0631 \u0641\u062a\u0646\u06c1 \u0648\u0641\u0633\u0627\u062f \u067e\u06be\u06cc\u0644\u0627\u06cc\u0627 \u062c\u0627\u0626\u06d2\u060c \u0627\u0633\u06d2 \u06cc\u06c1 \u0628\u0631\u062f\u0627\u0634\u062a \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u06a9\u06c1 \u0627\u0633 \u06a9\u06d2 \u0628\u0646\u062f\u0648\u06ba \u06a9\u0648 \u0628\u06d2 \u0642\u0635\u0648\u0631 \u062a\u0628\u0627\u06c1 \u0648\u0628\u0631\u0628\u0627\u062f \u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2\u060c \u067e\u0633 \u062c\u0648 \u06af\u0631\u0648\u06c1 \u0628\u063a\u06cc\u0631 \u06a9\u0633\u06cc \u062d\u0631\u0635 \u0648\u0637\u0645\u0639 \u06a9\u06d2 \u0645\u062d\u0636 \u062e\u062f\u0627 \u06a9\u06cc \u0631\u0636\u0627 \u06a9\u06cc \u062e\u0627\u0637\u0631 \u062f\u0646\u06cc\u0627 \u06a9\u0648 \u0627\u0633 \u0641\u062a\u0646\u06c1 \u0633\u06d2 \u067e\u0627\u06a9\u0631 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06be\u0691\u0627 \u06c1\u0648\u062c\u0627\u0626\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u0646\u06cc\u06a9 \u06a9\u0627\u0645 \u0645\u06cc\u06ba \u0627\u067e\u0646\u0627 \u0633\u0628 \u06a9\u0686\u06be \u0642\u0631\u0628\u0627\u0646 \u06a9\u0631\u062f\u06d2\u060c \u0627\u0633 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u0627\u0644\u0644\u06c1 \u06a9\u06cc \u0645\u062d\u0628\u062a\u060c \u0627\u0644\u0644\u06c1 \u06a9\u06cc \u0631\u0636\u0627 \u0645\u0646\u062f\u06cc \u06a9\u0627 \u0645\u0633\u062a\u062d\u0642 \u06a9\u0648\u0646 \u06c1\u0648\u0633\u06a9\u062a\u0627 \u06c1\u06d2\u061f \u0627\u0633 \u0645\u0636\u0645\u0648\u0646 \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u0627\u0633\u06cc \u0641\u0636\u06cc\u0644\u062a \u0648\u062d\u0642\u06cc\u0642\u062a \u06a9\u0648 \u0633\u0645\u062c\u06be\u0627\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0646\u06cc\u06a9\u06cc \u06a9\u06d2 \u0642\u06cc\u0627\u0645 \u0648 \u0628\u0642\u0627 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0633\u0628 \u0633\u06d2 \u0627\u06c1\u0645 \u0686\u06cc\u0632 \u0627\u0633 \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0633\u0686\u06cc \u0642\u0631\u0628\u0627\u0646\u06cc \u06a9\u06cc \u0631\u0648\u062d \u06c1\u06d2 \u0627\u0648\u0631 \u062c\u0633 \u0642\u0648\u0645 \u0633\u06d2 \u06cc\u06c1 \u0631\u0648\u062d \u0646\u06a9\u0644 \u062c\u0627\u062a\u06cc \u06c1\u06d2\u060c \u0648\u06c1 \u0628\u06c1\u062a \u062c\u0644\u062f\u0628\u062f\u06cc \u0633\u06d2 \u0645\u063a\u0644\u0648\u0628 \u06c1\u0648\u06a9\u0631 \u062a\u0628\u0627\u06c1 \u0648\u0628\u0631\u0628\u0627\u062f \u06c1\u0648\u062c\u0627\u062a\u06cc \u06c1\u06d2\u06d4<\/p>\n\n\n\n<p><strong>***<\/strong><\/p>\n\n\n\n<p><strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/strong><\/p>\n\n\n\n<p>\u0645\u0627\u06c1\u0646\u0627\u0645\u06c1 \u062f\u0627\u0631\u0627\u0644\u0639\u0644\u0648\u0645 \u200f\u060c \u0634\u0645\u0627\u0631\u06c1 12 \u060c \u062c\u0644\u062f: 95 \u200f\u060c \u0645\u062d\u0631\u0645 \u0627\u0644\u062d\u0631\u0627\u0645 1433 \u06c1\u062c\u0631\u06cc \u0645\u0637\u0627\u0628\u0642 \u062f\u0633\u0645\u0628\u0631 2011\u0621 <strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0632:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0645\u0648\u0644\u0627\u0646\u0627\u0646\u0635\u06cc\u0631\u0627\u0644\u062f\u06cc\u0646 \u0642\u0627\u0633\u0645\u06cc \u0648\u0644\u06cc\u062f\u067e\u0648\u0631\u06cc\u060c\u0627\u0633\u062a\u0627\u0630 \u0645\u062f\u0631\u0633\u06c1 \u062f\u0627\u0631\u0627\u0644\u0639\u0644\u0648\u0645 \u0645\u062d\u0645\u062f\u06cc\u06c1 \u0642\u0635\u0628\u06c1 \u06af\u062f\u0631\u067e\u0648\u0631 \u0627\u0646\u0633\u0627\u0646 \u06a9\u06cc \u062c\u0627\u0646 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u0627 \u062e\u0648\u0646 \u0645\u062d\u062a\u0631\u0645 \u06c1\u06d2\u060c \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0633\u0627\u0631\u06d2 \u0645\u0630\u0627\u06c1\u0628 \u0645\u06cc\u06ba \u0627\u062d\u062a\u0631\u0627\u0645\u0650 \u0646\u0641\u0633<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,45],"tags":[293],"class_list":["post-1540","post","type-post","status-publish","format-standard","hentry","category-14","category-45","tag-monthly-darul-uloom-december-2011"],"_links":{"self":[{"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/posts\/1540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/comments?post=1540"}],"version-history":[{"count":1,"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/posts\/1540\/revisions"}],"predecessor-version":[{"id":1541,"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/posts\/1540\/revisions\/1541"}],"wp:attachment":[{"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/media?parent=1540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/categories?post=1540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/darululoom-deoband.com\/urduarticles\/wp-json\/wp\/v2\/tags?post=1540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}